{"id":792,"count":1,"description":"","link":"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/","name":"right to life includes right to livelihood","slug":"right-to-life-includes-right-to-livelihood","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>right to life includes right to livelihood Archives - LexForti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"right to life includes right to livelihood Archives - LexForti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/\" \/>\n<meta property=\"og:site_name\" content=\"LexForti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/\",\"url\":\"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/\",\"name\":\"right to life includes right to livelihood Archives - LexForti\",\"isPartOf\":{\"@id\":\"https:\/\/lexforti.com\/legal-news\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lexforti.com\/legal-news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"right to life includes right to livelihood\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lexforti.com\/legal-news\/#website\",\"url\":\"https:\/\/lexforti.com\/legal-news\/\",\"name\":\"LexForti\",\"description\":\"Legal\",\"publisher\":{\"@id\":\"https:\/\/lexforti.com\/legal-news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lexforti.com\/legal-news\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lexforti.com\/legal-news\/#organization\",\"name\":\"LexForti Legal News & Journal\",\"url\":\"https:\/\/lexforti.com\/legal-news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lexforti.com\/legal-news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/lexforti.com\/legal-news\/wp-content\/uploads\/2020\/08\/159134300345793876.png?fit=404%2C404&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/lexforti.com\/legal-news\/wp-content\/uploads\/2020\/08\/159134300345793876.png?fit=404%2C404&ssl=1\",\"width\":404,\"height\":404,\"caption\":\"LexForti Legal News & Journal\"},\"image\":{\"@id\":\"https:\/\/lexforti.com\/legal-news\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Lexforti\/\",\"https:\/\/www.instagram.com\/lexforti\/\",\"https:\/\/www.linkedin.com\/company\/lex-forti\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"right to life includes right to livelihood Archives - LexForti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/","og_locale":"en_US","og_type":"article","og_title":"right to life includes right to livelihood Archives - LexForti","og_url":"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/","og_site_name":"LexForti","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/","url":"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/","name":"right to life includes right to livelihood Archives - LexForti","isPartOf":{"@id":"https:\/\/lexforti.com\/legal-news\/#website"},"breadcrumb":{"@id":"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lexforti.com\/legal-news\/tag\/right-to-life-includes-right-to-livelihood\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lexforti.com\/legal-news\/"},{"@type":"ListItem","position":2,"name":"right to life includes right to livelihood"}]},{"@type":"WebSite","@id":"https:\/\/lexforti.com\/legal-news\/#website","url":"https:\/\/lexforti.com\/legal-news\/","name":"LexForti","description":"Legal","publisher":{"@id":"https:\/\/lexforti.com\/legal-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lexforti.com\/legal-news\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lexforti.com\/legal-news\/#organization","name":"LexForti Legal News & Journal","url":"https:\/\/lexforti.com\/legal-news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lexforti.com\/legal-news\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/lexforti.com\/legal-news\/wp-content\/uploads\/2020\/08\/159134300345793876.png?fit=404%2C404&ssl=1","contentUrl":"https:\/\/i2.wp.com\/lexforti.com\/legal-news\/wp-content\/uploads\/2020\/08\/159134300345793876.png?fit=404%2C404&ssl=1","width":404,"height":404,"caption":"LexForti Legal News & Journal"},"image":{"@id":"https:\/\/lexforti.com\/legal-news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Lexforti\/","https:\/\/www.instagram.com\/lexforti\/","https:\/\/www.linkedin.com\/company\/lex-forti\/"]}]}},"_links":{"self":[{"href":"https:\/\/lexforti.com\/legal-news\/wp-json\/wp\/v2\/tags\/792"}],"collection":[{"href":"https:\/\/lexforti.com\/legal-news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lexforti.com\/legal-news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lexforti.com\/legal-news\/wp-json\/wp\/v2\/posts?tags=792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}